{"id":265948,"date":"2026-01-08T14:22:28","date_gmt":"2026-01-08T13:22:28","guid":{"rendered":"https:\/\/www.jootjeshaakcadeautjes.nl\/?post_type=product&#038;p=265948"},"modified":"2026-08-27T00:36:47","modified_gmt":"2026-08-26T22:36:47","slug":"durable-coral-kleur-2106-peacock-blue","status":"publish","type":"product","link":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/product\/durable-coral-color-2106-peacock-blue\/","title":{"rendered":"Durable Coral &#8211; Kleur 2106 Peacock Blue"},"content":{"rendered":"<h1>Durable Coral &#8211; Kleur 2106 Peacock Blue<\/h1>\n<p>Durable Coral is een garen van 100% gemerceriseerde katoen met een lichte glans. De zijdeachtige uitstraling geeft je haak- en breiwerk een extra luxe uitstraling. De haakkatoen bestaat uit 100% gemerceriseerd katoen. Geschikt voor het haken of breien van Amigurumi \/ knuffeltjes voor baby&#8217;s. Perfect voor het maken van kraamcadeautjes of cadeautjes voor babyshower.<\/p>\n<p>Kleur: 2106 Peacock Blue<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durable Coral &#8211; 2106 Peacock Blue<br \/>\n100% Mercerized cotton<\/p>\n<table border=\"0\">\n<tbody>\n<tr>\n<td>Material<\/td>\n<td>100% cotton<\/td>\n<\/tr>\n<tr>\n<td>Weight<\/td>\n<td>50 g<\/td>\n<\/tr>\n<tr>\n<td>Length<\/td>\n<td>approx. 125 m<\/td>\n<\/tr>\n<tr>\n<td>Recommended needle<\/td>\n<td>2.5 &#8211; 3 mm<\/td>\n<\/tr>\n<tr>\n<td>Gauge 10 x 10 cm<\/td>\n<td>24 stitches x 36 rows<\/td>\n<\/tr>\n<tr>\n<td>Machine wash<\/td>\n<td>30\u00b0C<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":265952,"template":"","meta":[],"product_brand":[],"product_cat":[6957,592,657],"product_tag":[670,18955,327,138,195,2983,6072,666,4459,46,937,6950,665,344,18956,667],"class_list":["post-265948","product","type-product","status-publish","has-post-thumbnail","product_cat-durable-coral-wol-garen-baby","product_cat-hobbymaterialen-haakbenodigdheden","product_cat-haakkatoen-garen-wol","product_tag-100-katoen","product_tag-18955","product_tag-amigurumi","product_tag-baby","product_tag-breien","product_tag-coral","product_tag-durable","product_tag-garen","product_tag-groothandel","product_tag-haken","product_tag-haken-voor-de-baby","product_tag-holly","product_tag-katoen","product_tag-kleur","product_tag-peacock-blue","product_tag-wol","product_shipping_class-pakketverzending-noodzakelijk","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":12,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Durable Coral - Color 2106 Peacock Blue - Jootjes Hook gifts<\/title>\n<meta name=\"description\" content=\"Durable Coral yarn - Colour 2106 Peacock Blue, available straight from stock. Perfect for crocheting baby items such as plush\/amigurumi and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Durable Coral - Color 2106 Peacock Blue\" \/>\n<meta property=\"og:description\" content=\"Durable Coral yarn - Colour 2106 Peacock Blue, available straight from stock. Perfect for crocheting baby items such as plush\/amigurumi and more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/\" \/>\n<meta property=\"og:site_name\" content=\"Jootjes Haakcadeautjes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-26T22:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2026\/01\/durable-coral-2106-peacock-blue.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prijs\" \/>\n\t<meta name=\"twitter:data1\" content=\"&euro;2.45 Incl. BTW\" \/>\n\t<meta name=\"twitter:label2\" content=\"Beschikbaarheid\" \/>\n\t<meta name=\"twitter:data2\" content=\"Op voorraad\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/\",\"name\":\"Durable Coral - Kleur 2106 Peacock Blue - Jootjes Haakcadeautjes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/d1dyryakdmle7o.cloudfront.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/durable-coral-2106-peacock-blue.webp\",\"datePublished\":\"2026-01-08T13:22:28+00:00\",\"dateModified\":\"2026-08-26T22:36:47+00:00\",\"description\":\"Durable Coral garen - Kleur 2106 Peacock Blue, leverbaar direct uit voorraad. Perfect voor het haken voor de baby, zoals knuffel \\\/ amigurumi en meer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/d1dyryakdmle7o.cloudfront.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/durable-coral-2106-peacock-blue.webp\",\"contentUrl\":\"https:\\\/\\\/d1dyryakdmle7o.cloudfront.net\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/durable-coral-2106-peacock-blue.webp\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/product\\\/durable-coral-kleur-2106-peacock-blue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Groothandel in Siliconen Kralen &#8211; Zakelijk en Particulier\",\"item\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/groothandel-siliconen-kralen-nederland-belgie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Durable Coral &#8211; Kleur 2106 Peacock Blue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/\",\"name\":\"Jootjes Haakcadeautjes\",\"description\":\"Groothandel in siliconen kralen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#organization\",\"name\":\"Jootjes Haakcadeautjes\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d1dyryakdmle7o.cloudfront.net\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-rond.png\",\"contentUrl\":\"https:\\\/\\\/d1dyryakdmle7o.cloudfront.net\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-rond.png\",\"width\":1222,\"height\":1222,\"caption\":\"Jootjes Haakcadeautjes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"2.45\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"DUR-COR-2106\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Durable Coral - Color 2106 Peacock Blue - Jootjes Hook gifts","description":"Durable Coral yarn - Colour 2106 Peacock Blue, available straight from stock. Perfect for crocheting baby items such as plush\/amigurumi and more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/","og_locale":"nl_NL","og_type":"article","og_title":"Durable Coral - Color 2106 Peacock Blue","og_description":"Durable Coral yarn - Colour 2106 Peacock Blue, available straight from stock. Perfect for crocheting baby items such as plush\/amigurumi and more.","og_url":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/","og_site_name":"Jootjes Haakcadeautjes","article_modified_time":"2026-08-26T22:36:47+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2026\/01\/durable-coral-2106-peacock-blue.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prijs":"&euro;2.45 Incl. BTW","Beschikbaarheid":"Op voorraad"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/","name":"Durable Coral - Kleur 2106 Peacock Blue - Jootjes Haakcadeautjes","isPartOf":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/#primaryimage"},"image":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/#primaryimage"},"thumbnailUrl":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2026\/01\/durable-coral-2106-peacock-blue.webp","datePublished":"2026-01-08T13:22:28+00:00","dateModified":"2026-08-26T22:36:47+00:00","description":"Durable Coral garen - Kleur 2106 Peacock Blue, leverbaar direct uit voorraad. Perfect voor het haken voor de baby, zoals knuffel \/ amigurumi en meer.","breadcrumb":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/#primaryimage","url":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2026\/01\/durable-coral-2106-peacock-blue.webp","contentUrl":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2026\/01\/durable-coral-2106-peacock-blue.webp","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/product\/durable-coral-kleur-2106-peacock-blue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jootjeshaakcadeautjes.nl\/"},{"@type":"ListItem","position":2,"name":"Groothandel in Siliconen Kralen &#8211; Zakelijk en Particulier","item":"https:\/\/www.jootjeshaakcadeautjes.nl\/groothandel-siliconen-kralen-nederland-belgie\/"},{"@type":"ListItem","position":3,"name":"Durable Coral &#8211; Kleur 2106 Peacock Blue"}]},{"@type":"WebSite","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#website","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/","name":"Jootjes Haakcadeautjes","description":"Groothandel in siliconen kralen","publisher":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#organization","name":"Jootjes Haakcadeautjes","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2023\/05\/Logo-rond.png","contentUrl":"https:\/\/d1dyryakdmle7o.cloudfront.net\/wp-content\/uploads\/2023\/05\/Logo-rond.png","width":1222,"height":1222,"caption":"Jootjes Haakcadeautjes"},"image":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"2.45","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"DUR-COR-2106","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product\/265948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product\/265948\/revisions"}],"predecessor-version":[{"id":265956,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product\/265948\/revisions\/265956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/media\/265952"}],"wp:attachment":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/media?parent=265948"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product_brand?post=265948"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product_cat?post=265948"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/en\/wp-json\/wp\/v2\/product_tag?post=265948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}