{"id":12923,"count":18,"description":"Grossiste perles de s\u00e9curit\u00e9 pour peluches : une large gamme pour les projets cr\u00e9atifs\nChez JootjesHaakcadeautjes.nl, vous trouverez une large gamme d'yeux de s\u00e9curit\u00e9, id\u00e9aux pour crocheter des peluches et des amigurumi. Ces yeux cr\u00e9ent l'illusion d'yeux en perles brillantes et permettent de donner facilement une belle apparence \u00e0 votre poup\u00e9e ou \u00e0 votre peluche. D\u00e9couvrez notre collection d'\u0153illets noirs de diff\u00e9rentes tailles, ainsi que des \u0153illets de s\u00e9curit\u00e9 color\u00e9s.\nQualit\u00e9 et s\u00e9curit\u00e9 d'abord : nos yeux sur la s\u00e9curit\u00e9\nChez JootjesHaakcadeautjes.nl, la s\u00e9curit\u00e9 passe avant tout. Ces \u0153illets sont \u00e0 la fois incroyablement bon march\u00e9 et le choix le plus s\u00fbr du march\u00e9. Nous avons d\u00e9lib\u00e9r\u00e9ment choisi des \u0153illets de s\u00e9curit\u00e9 avec une fermeture de haute qualit\u00e9 qu'il est pratiquement impossible de desserrer. Par rapport \u00e0 de nombreuses autres options sur le march\u00e9, chez JootjesHaakcadeautjes.co.uk vous pouvez \u00eatre s\u00fbr d'obtenir des \u0153illets qui se ferment correctement et qui sont s\u00fbrs.\nNos conseils pour une utilisation s\u00fbre : \u0152illets pour le crochet et le tricot\nN\u00e9anmoins, nous recommandons d'\u00e9viter les yeux de s\u00e9curit\u00e9 l\u00e2ches sur les jeunes enfants &lt;3 ans. Nous recommandons de fixer les \u0153illets sur le doudou pendant le processus de crochet et de tricot, par exemple par broderie. En effet, les jeunes enfants ont tendance \u00e0 se mordre les yeux et, avec le temps, ils peuvent \u00eatre endommag\u00e9s par l'usure. Bien que nos yeux de s\u00e9curit\u00e9 soient de haute qualit\u00e9, nous ne voulons pas que les jeunes enfants aient des ennuis avec ces yeux. Si vous souhaitez utiliser des yeux de s\u00e9curit\u00e9, surveillez toujours votre enfant lorsqu'il joue avec le produit. Jootjes Haakcadeautjes n'est donc en aucun cas responsable de tout dommage (cons\u00e9cutif) r\u00e9sultant d'une utilisation incorrecte de ce produit.\nConfirmation s\u00fbre : la certitude dans la cr\u00e9ativit\u00e9\nChez JootjesHaakcadeautjes.nl, nous fournissons non seulement des \u0153illets de s\u00e9curit\u00e9 de haute qualit\u00e9, mais aussi une s\u00e9curit\u00e9 dans le processus de fixation. Les \u0153illets de s\u00e9curit\u00e9 doivent \u00eatre fix\u00e9s avec le c\u00f4t\u00e9 droit et plat de l'attache vers l'ouvrage de crochet. Ce n'est qu'\u00e0 ce moment-l\u00e0 que l'\u0153il de s\u00e9curit\u00e9 est vraiment bien fix\u00e9 ! Nos \u0153illets sont con\u00e7us pour une fermeture s\u00fbre, vous permettant de commencer vos projets de crochet et de tricot en toute confiance.\nCommandez facilement chez Jootjes Haakcadeautjes : Livraison rapide et mat\u00e9riel d'artisanat\nCommandez votre gros chez Jootjes Haakcadeautjes, command\u00e9 aujourd'hui avant 16:00 est exp\u00e9di\u00e9 aujourd'hui. Cela signifie g\u00e9n\u00e9ralement une livraison le lendemain. Nous sommes facilement accessibles en cas de questions. Outre les yeux de s\u00e9curit\u00e9, vous trouverez \u00e9galement tout le mat\u00e9riel de loisirs n\u00e9cessaire au crochet et au tricot, comme du fil de crochet durable, des disques de hochet, des perles de hochet, des cloches, des aiguilles \u00e0 crochet et bien d'autres choses encore. D\u00e9couvrez d\u00e8s aujourd'hui notre gamme d'yeux de s\u00e9curit\u00e9 et d'autres mat\u00e9riaux de loisirs cr\u00e9atifs et donnez \u00e0 vos peluches et \u00e0 vos amigurumi un aspect professionnel et s\u00fbr.","link":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/","name":"\u0152il de s\u00e9curit\u00e9 pour les peluches","slug":"oeil-de-securite-pour-les-peluches","taxonomy":"product_cat","parent":12308,"meta":[],"menu_order":157,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0152il de s\u00e9curit\u00e9 pour les peluches Archives - Jootjes Haakcadeautjes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0152il de s\u00e9curit\u00e9 pour les peluches Archives\" \/>\n<meta property=\"og:description\" content=\"Grossiste perles de s\u00e9curit\u00e9 pour peluches : une large gamme pour les projets cr\u00e9atifs Chez JootjesHaakcadeautjes.nl, vous trouverez une large gamme d&#8217;yeux de s\u00e9curit\u00e9, id\u00e9aux pour crocheter des peluches et des amigurumi. Ces yeux cr\u00e9ent l&#8217;illusion d&#8217;yeux en perles brillantes et permettent de donner facilement une belle apparence \u00e0 votre poup\u00e9e ou \u00e0 votre peluche. D\u00e9couvrez notre collection d&#8217;\u0153illets noirs de diff\u00e9rentes tailles, ainsi que des \u0153illets de s\u00e9curit\u00e9 color\u00e9s. Qualit\u00e9 et s\u00e9curit\u00e9 d&#8217;abord : nos yeux sur la s\u00e9curit\u00e9 Chez JootjesHaakcadeautjes.nl, la s\u00e9curit\u00e9 passe avant tout. Ces \u0153illets sont \u00e0 la fois incroyablement bon march\u00e9 et le choix le plus s\u00fbr du march\u00e9. Nous avons d\u00e9lib\u00e9r\u00e9ment choisi des \u0153illets de s\u00e9curit\u00e9 avec une fermeture de haute qualit\u00e9 qu&#8217;il est pratiquement impossible de desserrer. Par rapport \u00e0 de nombreuses autres options sur le march\u00e9, chez JootjesHaakcadeautjes.co.uk vous pouvez \u00eatre s\u00fbr d&#8217;obtenir des \u0153illets qui se ferment correctement et qui sont s\u00fbrs. Nos conseils pour une utilisation s\u00fbre : \u0152illets pour le crochet et le tricot N\u00e9anmoins, nous recommandons d&#8217;\u00e9viter les yeux de s\u00e9curit\u00e9 l\u00e2ches sur les jeunes enfants &lt;3 ans. Nous recommandons de fixer les \u0153illets sur le doudou pendant le processus de crochet et de tricot, par exemple par broderie. En effet, les jeunes enfants ont tendance \u00e0 se mordre les yeux et, avec le temps, ils peuvent \u00eatre endommag\u00e9s par l&#8217;usure. Bien que nos yeux de s\u00e9curit\u00e9 soient de haute qualit\u00e9, nous ne voulons pas que les jeunes enfants aient des ennuis avec ces yeux. Si vous souhaitez utiliser des yeux de s\u00e9curit\u00e9, surveillez toujours votre enfant lorsqu&#8217;il joue avec le produit. Jootjes Haakcadeautjes n&#8217;est donc en aucun cas responsable de tout dommage (cons\u00e9cutif) r\u00e9sultant d&#8217;une utilisation incorrecte de ce produit. Confirmation s\u00fbre : la certitude dans la cr\u00e9ativit\u00e9 Chez JootjesHaakcadeautjes.nl, nous fournissons non seulement des \u0153illets de s\u00e9curit\u00e9 de haute qualit\u00e9, mais aussi une s\u00e9curit\u00e9 dans le processus de fixation. Les \u0153illets de s\u00e9curit\u00e9 doivent \u00eatre fix\u00e9s avec le c\u00f4t\u00e9 droit et plat de l&#8217;attache vers l&#8217;ouvrage de crochet. Ce n&#8217;est qu&#8217;\u00e0 ce moment-l\u00e0 que l&#8217;\u0153il de s\u00e9curit\u00e9 est vraiment bien fix\u00e9 ! Nos \u0153illets sont con\u00e7us pour une fermeture s\u00fbre, vous permettant de commencer vos projets de crochet et de tricot en toute confiance. Commandez facilement chez Jootjes Haakcadeautjes : Livraison rapide et mat\u00e9riel d&#8217;artisanat Commandez votre gros chez Jootjes Haakcadeautjes, command\u00e9 aujourd&#8217;hui avant 16:00 est exp\u00e9di\u00e9 aujourd&#8217;hui. Cela signifie g\u00e9n\u00e9ralement une livraison le lendemain. Nous sommes facilement accessibles en cas de questions. Outre les yeux de s\u00e9curit\u00e9, vous trouverez \u00e9galement tout le mat\u00e9riel de loisirs n\u00e9cessaire au crochet et au tricot, comme du fil de crochet durable, des disques de hochet, des perles de hochet, des cloches, des aiguilles \u00e0 crochet et bien d&#8217;autres choses encore. D\u00e9couvrez d\u00e8s aujourd&#8217;hui notre gamme d&#8217;yeux de s\u00e9curit\u00e9 et d&#8217;autres mat\u00e9riaux de loisirs cr\u00e9atifs et donnez \u00e0 vos peluches et \u00e0 vos amigurumi un aspect professionnel et s\u00fbr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/\" \/>\n<meta property=\"og:site_name\" content=\"Jootjes Haakcadeautjes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/product-categorie\\\/materiel-de-bricolage-et-de-crochet\\\/oeil-de-securite-pour-les-peluches\\\/\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/product-categorie\\\/materiel-de-bricolage-et-de-crochet\\\/oeil-de-securite-pour-les-peluches\\\/\",\"name\":\"\u0152il de s\u00e9curit\u00e9 pour les peluches Archives - Jootjes Haakcadeautjes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/product-categorie\\\/materiel-de-bricolage-et-de-crochet\\\/oeil-de-securite-pour-les-peluches\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/product-categorie\\\/materiel-de-bricolage-et-de-crochet\\\/oeil-de-securite-pour-les-peluches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mat\u00e9riel de bricolage et de crochet\",\"item\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/product-categorie\\\/materiel-de-bricolage-et-de-crochet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0152il de s\u00e9curit\u00e9 pour les peluches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/\",\"name\":\"Jootjes Haakcadeautjes\",\"description\":\"Grossiste en perles de silicone\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#organization\",\"name\":\"Jootjes Haakcadeautjes\",\"url\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jootjes-haakcadeautjes-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-rond.png\",\"contentUrl\":\"https:\\\/\\\/jootjes-haakcadeautjes-media.s3.amazonaws.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Logo-rond.png\",\"width\":1222,\"height\":1222,\"caption\":\"Jootjes Haakcadeautjes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jootjeshaakcadeautjes.nl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0152il de s\u00e9curit\u00e9 pour les peluches Archives - Jootjes Haakcadeautjes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/","og_locale":"fr_FR","og_type":"article","og_title":"\u0152il de s\u00e9curit\u00e9 pour les peluches Archives","og_description":"Grossiste perles de s\u00e9curit\u00e9 pour peluches : une large gamme pour les projets cr\u00e9atifs Chez JootjesHaakcadeautjes.nl, vous trouverez une large gamme d&#8217;yeux de s\u00e9curit\u00e9, id\u00e9aux pour crocheter des peluches et des amigurumi. Ces yeux cr\u00e9ent l&#8217;illusion d&#8217;yeux en perles brillantes et permettent de donner facilement une belle apparence \u00e0 votre poup\u00e9e ou \u00e0 votre peluche. D\u00e9couvrez notre collection d&#8217;\u0153illets noirs de diff\u00e9rentes tailles, ainsi que des \u0153illets de s\u00e9curit\u00e9 color\u00e9s. Qualit\u00e9 et s\u00e9curit\u00e9 d&#8217;abord : nos yeux sur la s\u00e9curit\u00e9 Chez JootjesHaakcadeautjes.nl, la s\u00e9curit\u00e9 passe avant tout. Ces \u0153illets sont \u00e0 la fois incroyablement bon march\u00e9 et le choix le plus s\u00fbr du march\u00e9. Nous avons d\u00e9lib\u00e9r\u00e9ment choisi des \u0153illets de s\u00e9curit\u00e9 avec une fermeture de haute qualit\u00e9 qu&#8217;il est pratiquement impossible de desserrer. Par rapport \u00e0 de nombreuses autres options sur le march\u00e9, chez JootjesHaakcadeautjes.co.uk vous pouvez \u00eatre s\u00fbr d&#8217;obtenir des \u0153illets qui se ferment correctement et qui sont s\u00fbrs. Nos conseils pour une utilisation s\u00fbre : \u0152illets pour le crochet et le tricot N\u00e9anmoins, nous recommandons d&#8217;\u00e9viter les yeux de s\u00e9curit\u00e9 l\u00e2ches sur les jeunes enfants &lt;3 ans. Nous recommandons de fixer les \u0153illets sur le doudou pendant le processus de crochet et de tricot, par exemple par broderie. En effet, les jeunes enfants ont tendance \u00e0 se mordre les yeux et, avec le temps, ils peuvent \u00eatre endommag\u00e9s par l&#8217;usure. Bien que nos yeux de s\u00e9curit\u00e9 soient de haute qualit\u00e9, nous ne voulons pas que les jeunes enfants aient des ennuis avec ces yeux. Si vous souhaitez utiliser des yeux de s\u00e9curit\u00e9, surveillez toujours votre enfant lorsqu&#8217;il joue avec le produit. Jootjes Haakcadeautjes n&#8217;est donc en aucun cas responsable de tout dommage (cons\u00e9cutif) r\u00e9sultant d&#8217;une utilisation incorrecte de ce produit. Confirmation s\u00fbre : la certitude dans la cr\u00e9ativit\u00e9 Chez JootjesHaakcadeautjes.nl, nous fournissons non seulement des \u0153illets de s\u00e9curit\u00e9 de haute qualit\u00e9, mais aussi une s\u00e9curit\u00e9 dans le processus de fixation. Les \u0153illets de s\u00e9curit\u00e9 doivent \u00eatre fix\u00e9s avec le c\u00f4t\u00e9 droit et plat de l&#8217;attache vers l&#8217;ouvrage de crochet. Ce n&#8217;est qu&#8217;\u00e0 ce moment-l\u00e0 que l&#8217;\u0153il de s\u00e9curit\u00e9 est vraiment bien fix\u00e9 ! Nos \u0153illets sont con\u00e7us pour une fermeture s\u00fbre, vous permettant de commencer vos projets de crochet et de tricot en toute confiance. Commandez facilement chez Jootjes Haakcadeautjes : Livraison rapide et mat\u00e9riel d&#8217;artisanat Commandez votre gros chez Jootjes Haakcadeautjes, command\u00e9 aujourd&#8217;hui avant 16:00 est exp\u00e9di\u00e9 aujourd&#8217;hui. Cela signifie g\u00e9n\u00e9ralement une livraison le lendemain. Nous sommes facilement accessibles en cas de questions. Outre les yeux de s\u00e9curit\u00e9, vous trouverez \u00e9galement tout le mat\u00e9riel de loisirs n\u00e9cessaire au crochet et au tricot, comme du fil de crochet durable, des disques de hochet, des perles de hochet, des cloches, des aiguilles \u00e0 crochet et bien d&#8217;autres choses encore. D\u00e9couvrez d\u00e8s aujourd&#8217;hui notre gamme d&#8217;yeux de s\u00e9curit\u00e9 et d&#8217;autres mat\u00e9riaux de loisirs cr\u00e9atifs et donnez \u00e0 vos peluches et \u00e0 vos amigurumi un aspect professionnel et s\u00fbr.","og_url":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/","og_site_name":"Jootjes Haakcadeautjes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/","name":"\u0152il de s\u00e9curit\u00e9 pour les peluches Archives - Jootjes Haakcadeautjes","isPartOf":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/oeil-de-securite-pour-les-peluches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/"},{"@type":"ListItem","position":2,"name":"Mat\u00e9riel de bricolage et de crochet","item":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/product-categorie\/materiel-de-bricolage-et-de-crochet\/"},{"@type":"ListItem","position":3,"name":"\u0152il de s\u00e9curit\u00e9 pour les peluches"}]},{"@type":"WebSite","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#website","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/","name":"Jootjes Haakcadeautjes","description":"Grossiste en perles de silicone","publisher":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#organization","name":"Jootjes Haakcadeautjes","url":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/jootjes-haakcadeautjes-media.s3.amazonaws.com\/wp-content\/uploads\/2023\/05\/Logo-rond.png","contentUrl":"https:\/\/jootjes-haakcadeautjes-media.s3.amazonaws.com\/wp-content\/uploads\/2023\/05\/Logo-rond.png","width":1222,"height":1222,"caption":"Jootjes Haakcadeautjes"},"image":{"@id":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/wp-json\/wp\/v2\/product_cat\/12923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/wp-json\/wp\/v2\/product_cat\/12308"}],"wp:post_type":[{"href":"https:\/\/www.jootjeshaakcadeautjes.nl\/fr\/wp-json\/wp\/v2\/product?product_cat=12923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}